{"id":205,"count":1,"description":"","link":"https:\/\/alanyahomesforsale.com\/fi\/city\/alanya-tosmur-alanya-tosmur\/","name":"Alanya Tosmur","slug":"alanya-tosmur-alanya-tosmur","taxonomy":"property_city","parent":198,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alanya Tosmur arkistot - Alanya Homes For Sale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alanyahomesforsale.com\/fi\/city\/alanya-tosmur-alanya-tosmur\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alanya Tosmur arkistot - Alanya Homes For Sale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alanyahomesforsale.com\/fi\/city\/alanya-tosmur-alanya-tosmur\/\" \/>\n<meta property=\"og:site_name\" content=\"Alanya Homes For Sale\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/alanyahomesforsale.com\\\/city\\\/alanya-tosmur-alanya-tosmur\\\/\",\"url\":\"https:\\\/\\\/alanyahomesforsale.com\\\/city\\\/alanya-tosmur-alanya-tosmur\\\/\",\"name\":\"Alanya Tosmur arkistot - Alanya Homes For Sale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alanyahomesforsale.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alanyahomesforsale.com\\\/city\\\/alanya-tosmur-alanya-tosmur\\\/#breadcrumb\"},\"inLanguage\":\"fi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alanyahomesforsale.com\\\/city\\\/alanya-tosmur-alanya-tosmur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/alanyahomesforsale.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alanya Tosmur\",\"item\":\"https:\\\/\\\/alanyahomesforsale.com\\\/city\\\/alanya-tosmur\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alanya Tosmur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alanyahomesforsale.com\\\/#website\",\"url\":\"https:\\\/\\\/alanyahomesforsale.com\\\/\",\"name\":\"Alanya Homes For Sale\",\"description\":\"Alanya Homes For Sale\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alanyahomesforsale.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alanya Tosmur arkistot - Alanya Homes For Sale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alanyahomesforsale.com\/fi\/city\/alanya-tosmur-alanya-tosmur\/","og_locale":"fi_FI","og_type":"article","og_title":"Alanya Tosmur arkistot - Alanya Homes For Sale","og_url":"https:\/\/alanyahomesforsale.com\/fi\/city\/alanya-tosmur-alanya-tosmur\/","og_site_name":"Alanya Homes For Sale","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/alanyahomesforsale.com\/city\/alanya-tosmur-alanya-tosmur\/","url":"https:\/\/alanyahomesforsale.com\/city\/alanya-tosmur-alanya-tosmur\/","name":"Alanya Tosmur arkistot - Alanya Homes For Sale","isPartOf":{"@id":"https:\/\/alanyahomesforsale.com\/#website"},"breadcrumb":{"@id":"https:\/\/alanyahomesforsale.com\/city\/alanya-tosmur-alanya-tosmur\/#breadcrumb"},"inLanguage":"fi"},{"@type":"BreadcrumbList","@id":"https:\/\/alanyahomesforsale.com\/city\/alanya-tosmur-alanya-tosmur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/alanyahomesforsale.com\/"},{"@type":"ListItem","position":2,"name":"Alanya Tosmur","item":"https:\/\/alanyahomesforsale.com\/city\/alanya-tosmur\/"},{"@type":"ListItem","position":3,"name":"Alanya Tosmur"}]},{"@type":"WebSite","@id":"https:\/\/alanyahomesforsale.com\/#website","url":"https:\/\/alanyahomesforsale.com\/","name":"Alanya Homes For Sale","description":"Alanya Homes For Sale","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alanyahomesforsale.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"}]}},"_links":{"self":[{"href":"https:\/\/alanyahomesforsale.com\/fi\/wp-json\/wp\/v2\/property_city\/205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alanyahomesforsale.com\/fi\/wp-json\/wp\/v2\/property_city"}],"about":[{"href":"https:\/\/alanyahomesforsale.com\/fi\/wp-json\/wp\/v2\/taxonomies\/property_city"}],"up":[{"embeddable":true,"href":"https:\/\/alanyahomesforsale.com\/fi\/wp-json\/wp\/v2\/property_city\/198"}],"wp:post_type":[{"href":"https:\/\/alanyahomesforsale.com\/fi\/wp-json\/wp\/v2\/properties?property_city=205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}